{"id":5717,"date":"2019-06-21T08:20:36","date_gmt":"2019-06-21T13:20:36","guid":{"rendered":"https:\/\/www.facturadorelectronico.com\/blog\/?p=5717"},"modified":"2024-06-18T16:40:56","modified_gmt":"2024-06-18T21:40:56","slug":"pueden-catalogar-a-mi-negocio-como-edos","status":"publish","type":"post","link":"https:\/\/www.facturadorelectronico.com\/blog\/2019\/06\/pueden-catalogar-a-mi-negocio-como-edos.html","title":{"rendered":"\u00bfPueden catalogar a mi negocio como EDOS?"},"content":{"rendered":"<p>Desde que en el a\u00f1o 2010 el Servicio de Administraci\u00f3n Tributaria (SAT) implement\u00f3 la figura de los comprobantes fiscales digitales por internet (CFDI), empresas mexicanas incursionaron en el desarrollo de <a href=\"https:\/\/www.facturadorelectronico.com\/software-de-contabilidad-electronica.html\">contabilidad digital<\/a> que permitiera facilitar las operaciones administrativas seg\u00fan las nuevas disposiciones.<\/p>\n<p>M\u00e1s a\u00fan, luego de que a partir de 2014 la emisi\u00f3n de los CFDI se hiciera obligatoria, M\u00e9xico se convirti\u00f3 en referente en cuanto al tema de facturaci\u00f3n electr\u00f3nica reportando un promedio de 160 comprobantes fiscales emitidos de forma electr\u00f3nica por segundo, cifra que llegar\u00eda en 2018 a 210.9.<\/p>\n<p>Este impresionante avance en tan s\u00f3lo cuatro a\u00f1os hace de nuestro pa\u00eds l\u00edder a nivel mundial reportando alrededor de 5 mil millones de facturas en l\u00ednea anualmente.<\/p>\n<p>Sin embargo, si bien esto reduce en buena medida la evasi\u00f3n fiscal y los fraudes por lavado de dinero, adem\u00e1s de ser un punto a favor de la transparencia en operaciones de los sectores p\u00fablicos y privados, existen ciertas compa\u00f1\u00edas que han aprovechado este esquema tributario para hacer de las facturas electr\u00f3nicas una mercanc\u00eda.<\/p>\n<h2>\u00bfQu\u00e9 consecuencias puede tener la compra y venta de facturas?<\/h2>\n<p>Tanto la compra como la venta de facturas, expedidas por las llamadas EFOS (empresas facturadoras de operaciones simuladas), es un delito que puede ser castigado hasta con seis a\u00f1os de c\u00e1rcel, seg\u00fan lo dispuesto en C\u00f3digo Fiscal de la Federaci\u00f3n (CFF).<\/p>\n<p>Este decreto, publicado apenas el d\u00eda 16 del pasado mes en el Diario Oficial de la Federaci\u00f3n (DOF) y cuya entrada en vigor tuvo lugar al d\u00eda siguiente, pretende acabar con el negocio de los \u201cfactureros\u201d, que no s\u00f3lo defraudan al fisco, sino que con sus acciones promueven incluso las operaciones del crimen organizado, que lava el dinero de sus actividades por este medio.<\/p>\n<h2>\u00bfC\u00f3mo puede afectar a mi negocio?<\/h2>\n<p>En ocasiones, sin plena intenci\u00f3n de cometer fraude, personas f\u00edsicas o morales con actividades comerciales ceden su informaci\u00f3n confidencial \u2013como la firma electr\u00f3nica\u2014 a contadores o proveedores de servicios de facturaci\u00f3n, esto para evitarse l\u00edos administrativos que, no obstante, puede presentar varios riesgos e implicaciones penales.<\/p>\n<p>El mal uso de esa informaci\u00f3n por parte de terceros o el desconocimiento de que un proveedor de facturas con el que se trabaja pertenece a las EFOS, puede ocasionar la inconsecuencia de los CFDI\u2019s presentados ante el SAT para deducir impuestos, lo que podr\u00eda generarte cargos fiscales y multas, adem\u00e1s de que podr\u00edas ser investigado como empresa que deduce operaciones simuladas (EDOS).<\/p>\n<h2>\u00bfQu\u00e9 hacer si catalogan a mi negocio como EDOS?<\/h2>\n<p>La soluci\u00f3n aqu\u00ed es demostrar que los bienes o servicios reflejados en las facturas corresponden efectivamente a compras realizadas por la empresa, aunque en ocasiones la falta de contratos ante notario y hasta documentaci\u00f3n no membretada puede levantar las sospechas de las autoridades fiscales.<\/p>\n<p>De esta manera, lo m\u00e1s recomendable es contar con un respaldo de todos los archivos y papeles que, en alg\u00fan momento dado, puedan servir de prueba ante el SAT, cuidando siempre guardar el mejor orden de estos y prestar atenci\u00f3n a detalles de nombre comercial, raz\u00f3n social, domicilio fiscal, etc\u00e9tera.<\/p>\n<p>Una forma m\u00e1s de prevenirlo es contar con un proveedor confiable, en Facturador.com tu informaci\u00f3n estar\u00e1 siempre a salvo. Nos encontramos dentro de la lista de proveedores autorizados por el SAT para emitir facturas. Cont\u00e1ctanos y recibe una asesor\u00eda personalizada para que puedas disipar tus dudas y empieces a realizar tu contabilidad electr\u00f3nica de la manera m\u00e1s f\u00e1cil y segura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde que en el a\u00f1o 2010 el Servicio de Administraci\u00f3n Tributaria (SAT) implement\u00f3 la figura de los comprobantes fiscales digitales por internet (CFDI), empresas mexicanas incursionaron en el desarrollo de contabilidad digital que permitiera facilitar las operaciones administrativas seg\u00fan las [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,2],"tags":[],"class_list":["post-5717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contabilidad-electronica","category-facturas-electronicas"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/www.facturadorelectronico.com\/blog\/wp-content\/uploads\/2019\/06\/pueden-catalogar-negocio-edos.jpg","_links":{"self":[{"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/posts\/5717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/comments?post=5717"}],"version-history":[{"count":2,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/posts\/5717\/revisions"}],"predecessor-version":[{"id":9137,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/posts\/5717\/revisions\/9137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/media\/5721"}],"wp:attachment":[{"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/media?parent=5717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/categories?post=5717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/tags?post=5717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}