{"id":4593,"date":"2017-06-23T09:30:03","date_gmt":"2017-06-23T14:30:03","guid":{"rendered":"http:\/\/www.facturadorelectronico.com\/blog\/?p=4593"},"modified":"2025-04-03T15:30:35","modified_gmt":"2025-04-03T21:30:35","slug":"urge-capacitacion-para-implementar-nuevas-facturas","status":"publish","type":"post","link":"https:\/\/www.facturadorelectronico.com\/blog\/2017\/06\/urge-capacitacion-para-implementar-nuevas-facturas.html","title":{"rendered":"Urge capacitaci\u00f3n para implementar nuevas facturas"},"content":{"rendered":"<p>El trabajo interdisciplinario ser\u00e1 vital para comenzar la migraci\u00f3n a la nueva versi\u00f3n de la factura. De acuerdo con Adri\u00e1n Guarneros Tapia, Administrador General de Servicios al Contribuyente de Servicio de Administraci\u00f3n Tributaria, deber\u00e1 de existir una mayor coordinaci\u00f3n entre las \u00e1reas operativas,\u00a0 inform\u00e1ticas y contables de los negocios para efectuar los cambios necesarios para la emisi\u00f3n de las facturas 3.3.<\/p>\n<p>Los cambios entrar\u00e1n en vigor el 1 de julio y se tendr\u00e1 hasta el 30 de noviembre para realizar la migraci\u00f3n total. Dichas variaciones implican modificaciones en las metodolog\u00edas de trabajo de las empresas quienes se ver\u00e1n en la necesidad de destinar recursos humanos y econ\u00f3micos para lograr la implementaci\u00f3n con \u00e9xito.<\/p>\n<p>Los principales temores que han externado representantes de empresarios y contadores es la poca capacitaci\u00f3n que se ha brindado para realizar este procesos. A pesar de que el SAT report\u00f3 que se trabaja en mesas con el Consejo Coordinador Empresarial, el Instituto Mexicano de Contadores P\u00fablicos, la Asociaci\u00f3n Mexicana de Proveedores Autorizados de Certificaci\u00f3n y la Asociaci\u00f3n Mexicana de la Industria de Tecnolog\u00edas de la Informaci\u00f3n, muchos temen que la informaci\u00f3n no llegue a tiempo a todas las \u00e1reas correspondientes, por lo que solicitan la capacitaci\u00f3n para que los contadores conozcan el nuevo esquema para <a href=\"https:\/\/www.facturadorelectronico.com\/blog\/2024\/12\/tips-para-descargar-facturas-facilmente.html\"><strong>descargar XML del SAT<\/strong><\/a> y todo lo que involucre el proceso para estar preparados.<\/p>\n<p>De acuerdo con un comunicado del SAT se reciben m\u00e1s de 6 mil millones de facturas que se utilizan para ofrecer servicios m\u00e1s automatizados a los contribuyentes pero existen inconsistencias en el esquema de emisi\u00f3n de las mismas, por lo cual se detect\u00f3 la necesidad de realizar una actualizaci\u00f3n.<\/p>\n<p>El SAT asegura que con los nuevos cambios se podr\u00e1n alinear procesos entre empresas, eliminar declaraciones, simplificar la emisi\u00f3n, evitar errores y agilizar los procesos de auditor\u00edas, este \u00faltimo beneficio impactar\u00e1 directamente a la efectividad de las autoridades ya que podr\u00e1n dise\u00f1ar modelos de riesgo m\u00e1s consistentes que les permitan tomar acciones contra la corrupci\u00f3n y la evasi\u00f3n detectando pr\u00e1cticas indebidas en la emisi\u00f3n y cancelaci\u00f3n de facturas, algo que con la factura actual no pueden realizar tan f\u00e1cilmente.<\/p>\n<p>De igual forma con la informaci\u00f3n que ser\u00e1 recabada a trav\u00e9s de estas nuevas facturas se podr\u00e1n simplificar las auditorias y garantizar que las revisiones sean m\u00e1s certeras y menos invasivas para el contribuyente.<\/p>\n<p>El Servicio de Administraci\u00f3n Tributaria exhort\u00f3 a las empresas y contribuyentes a conocer la documentaci\u00f3n y gu\u00edas de llenado de las facturas que ser\u00e1 publicado en su portal para tener una mayor penetraci\u00f3n de la informaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El trabajo interdisciplinario ser\u00e1 vital para comenzar la migraci\u00f3n a la nueva versi\u00f3n de la factura. De acuerdo con Adri\u00e1n Guarneros Tapia, Administrador General de Servicios al Contribuyente de Servicio de Administraci\u00f3n Tributaria, deber\u00e1 de existir una mayor coordinaci\u00f3n entre [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-4593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cfdi"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/www.facturadorelectronico.com\/blog\/wp-content\/uploads\/2017\/06\/capacitacion.jpg","_links":{"self":[{"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/posts\/4593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/comments?post=4593"}],"version-history":[{"count":3,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/posts\/4593\/revisions"}],"predecessor-version":[{"id":9799,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/posts\/4593\/revisions\/9799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/media\/4595"}],"wp:attachment":[{"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/media?parent=4593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/categories?post=4593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.facturadorelectronico.com\/blog\/wp-json\/wp\/v2\/tags?post=4593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}